{"id":222619,"date":"2026-03-13T11:29:21","date_gmt":"2026-03-13T09:29:21","guid":{"rendered":"https:\/\/odavprint.ee\/?post_type=product&#038;p=222619"},"modified":"2026-05-11T18:48:03","modified_gmt":"2026-05-11T15:48:03","slug":"bambu-lab-pla-matte-tuhahall-filament-pooliga","status":"publish","type":"product","link":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/","title":{"rendered":"Bambu Lab &#8211; PLA Matte, Tuhahall, Filament pooliga"},"content":{"rendered":"<p>Hulgi ostes v\u00f5idad rohkem!4 rulli \u2013 35% allahindlus6 rulli \u2013 45% allahindlus10 rulli \u2013 50% allahindlus<\/p>\n<p>PLA Matte filament Bambu Labilt on mattpinnaga ja biolagunev, mist\u00f5ttu sobib see suurep\u00e4raselt algajatele 3D-printimises. Selle tr\u00fckkimine on lihtne. Filamendi l\u00e4bim\u00f5\u00f5t on 1.75mm, tolerantsiga \u00b10.03mm. See \u00fchildub Bambu Lab&#8217;i automaatse materjalis\u00fcsteemiga (AMS) ja on saadaval mitmes v\u00e4rvitoonis, nii t\u00e4itekasseti kui ka pooliga. Filamendil on tihedus 1.31 g\/cm\u00b3, Vicati pehmenemistemperatuur 63\u00b0C ja t\u00f5mbetugevus 30 \u00b1 5 MPa.<br \/>\nRohkem infot<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hulgi ostes v\u00f5idad rohkem!4 rulli \u2013 35% allahindlus6 rulli \u2013 45% allahindlus10 rulli \u2013 50% allahindlus PLA Matte filament Bambu Labilt on mattpinnaga ja biolagunev, mist\u00f5ttu sobib see suurep\u00e4raselt algajatele 3D-printimises. Selle tr\u00fckkimine on lihtne. Filamendi l\u00e4bim\u00f5\u00f5t on 1.75mm, tolerantsiga \u00b10.03mm. See \u00fchildub Bambu Lab&#8217;i automaatse materjalis\u00fcsteemiga (AMS) ja on saadaval mitmes v\u00e4rvitoonis, nii t\u00e4itekasseti [&#8230;]\n","protected":false},"featured_media":222620,"template":"","meta":{"inline_featured_image":false},"product_cat":[39657],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.0 (Yoast SEO v23.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bambu Lab - PLA Matte, Tuhahall, Filament pooliga, hea hinnaga, osta e-pood - Odav Print<\/title>\n<meta name=\"description\" content=\"Osta Bambu Lab - PLA Matte, Tuhahall, Filament pooliga Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Bambu Lab - PLA Matte, Tuhahall, Filament pooliga jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bambu Lab - PLA Matte, Tuhahall, Filament pooliga\" \/>\n<meta property=\"og:description\" content=\"Osta Bambu Lab - PLA Matte, Tuhahall, Filament pooliga Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Bambu Lab - PLA Matte, Tuhahall, Filament pooliga jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/\" \/>\n<meta property=\"og:site_name\" content=\"Odav Print\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T15:48:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/odavprint.ee\/wp-content\/uploads\/2026\/03\/Bambu-lab-pla-matte-susimust-16.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;27.76\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/\",\"url\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/\",\"name\":\"Bambu Lab - PLA Matte, Tuhahall, Filament pooliga, hea hinnaga, osta e-pood - Odav Print\",\"isPartOf\":{\"@id\":\"https:\/\/odavprint.ee\/et\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2026\/03\/Bambu-lab-pla-matte-susimust-16.webp\",\"datePublished\":\"2026-03-13T09:29:21+00:00\",\"dateModified\":\"2026-05-11T15:48:03+00:00\",\"description\":\"Osta Bambu Lab - PLA Matte, Tuhahall, Filament pooliga Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Bambu Lab - PLA Matte, Tuhahall, Filament pooliga jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud\",\"breadcrumb\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#primaryimage\",\"url\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2026\/03\/Bambu-lab-pla-matte-susimust-16.webp\",\"contentUrl\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2026\/03\/Bambu-lab-pla-matte-susimust-16.webp\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odavprint.ee\/et\/esileht\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-pood\",\"item\":\"https:\/\/odavprint.ee\/et\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bambu Lab &#8211; PLA Matte, Tuhahall, Filament pooliga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odavprint.ee\/et\/#website\",\"url\":\"https:\/\/odavprint.ee\/et\/\",\"name\":\"Odav Print\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/odavprint.ee\/et\/#organization\"},\"alternateName\":\"Kassettide, toonerite t\u00e4itmine ja m\u00fc\u00fck.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odavprint.ee\/et\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"et\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/odavprint.ee\/et\/#organization\",\"name\":\"Odav Print O\u00dc\",\"url\":\"https:\/\/odavprint.ee\/et\/\",\"logo\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-organization-logo\"},\"address\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"59.4306504\",\"longitude\":\"24.8095743\"},\"telephone\":[\"53836926\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"info@odavprint.eu\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-place-address\",\"streetAddress\":\"Pae tn 28\",\"addressLocality\":\"Tallinn\",\"postalCode\":\"11415\",\"addressRegion\":\"Harjumaa\",\"addressCountry\":\"EE\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-organization-logo\",\"url\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2018\/10\/odavprint-logo-240.jpg\",\"contentUrl\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2018\/10\/odavprint-logo-240.jpg\",\"width\":240,\"height\":36,\"caption\":\"Odav Print O\u00dc\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"27.76\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Tallinn\" \/>\n<meta name=\"geo.position\" content=\"59.4306504;24.8095743\" \/>\n<meta name=\"geo.region\" content=\"Estonia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bambu Lab - PLA Matte, Tuhahall, Filament pooliga, hea hinnaga, osta e-pood - Odav Print","description":"Osta Bambu Lab - PLA Matte, Tuhahall, Filament pooliga Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Bambu Lab - PLA Matte, Tuhahall, Filament pooliga jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/","og_locale":"et_EE","og_type":"article","og_title":"Bambu Lab - PLA Matte, Tuhahall, Filament pooliga","og_description":"Osta Bambu Lab - PLA Matte, Tuhahall, Filament pooliga Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Bambu Lab - PLA Matte, Tuhahall, Filament pooliga jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud","og_url":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/","og_site_name":"Odav Print","article_modified_time":"2026-05-11T15:48:03+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/odavprint.ee\/wp-content\/uploads\/2026\/03\/Bambu-lab-pla-matte-susimust-16.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;27.76","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/","url":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/","name":"Bambu Lab - PLA Matte, Tuhahall, Filament pooliga, hea hinnaga, osta e-pood - Odav Print","isPartOf":{"@id":"https:\/\/odavprint.ee\/et\/#website"},"primaryImageOfPage":{"@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#primaryimage"},"image":{"@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#primaryimage"},"thumbnailUrl":"https:\/\/odavprint.ee\/wp-content\/uploads\/2026\/03\/Bambu-lab-pla-matte-susimust-16.webp","datePublished":"2026-03-13T09:29:21+00:00","dateModified":"2026-05-11T15:48:03+00:00","description":"Osta Bambu Lab - PLA Matte, Tuhahall, Filament pooliga Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Bambu Lab - PLA Matte, Tuhahall, Filament pooliga jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud","breadcrumb":{"@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#primaryimage","url":"https:\/\/odavprint.ee\/wp-content\/uploads\/2026\/03\/Bambu-lab-pla-matte-susimust-16.webp","contentUrl":"https:\/\/odavprint.ee\/wp-content\/uploads\/2026\/03\/Bambu-lab-pla-matte-susimust-16.webp","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odavprint.ee\/et\/esileht\/"},{"@type":"ListItem","position":2,"name":"E-pood","item":"https:\/\/odavprint.ee\/et\/shop\/"},{"@type":"ListItem","position":3,"name":"Bambu Lab &#8211; PLA Matte, Tuhahall, Filament pooliga"}]},{"@type":"WebSite","@id":"https:\/\/odavprint.ee\/et\/#website","url":"https:\/\/odavprint.ee\/et\/","name":"Odav Print","description":"Just another WordPress site","publisher":{"@id":"https:\/\/odavprint.ee\/et\/#organization"},"alternateName":"Kassettide, toonerite t\u00e4itmine ja m\u00fc\u00fck.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odavprint.ee\/et\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"et"},{"@type":["Organization","Place"],"@id":"https:\/\/odavprint.ee\/et\/#organization","name":"Odav Print O\u00dc","url":"https:\/\/odavprint.ee\/et\/","logo":{"@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-organization-logo"},"image":{"@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-organization-logo"},"address":{"@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"59.4306504","longitude":"24.8095743"},"telephone":["53836926"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"info@odavprint.eu"},{"@type":"PostalAddress","@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-place-address","streetAddress":"Pae tn 28","addressLocality":"Tallinn","postalCode":"11415","addressRegion":"Harjumaa","addressCountry":"EE"},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/odavprint.ee\/et\/product\/bambu-lab-pla-matte-tuhahall-filament-pooliga\/#local-main-organization-logo","url":"https:\/\/odavprint.ee\/wp-content\/uploads\/2018\/10\/odavprint-logo-240.jpg","contentUrl":"https:\/\/odavprint.ee\/wp-content\/uploads\/2018\/10\/odavprint-logo-240.jpg","width":240,"height":36,"caption":"Odav Print O\u00dc"}]},"product_price_amount":"27.76","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_condition":"new","geo.placename":"Tallinn","geo.position":{"lat":"59.4306504","long":"24.8095743"},"geo.region":"Estonia"},"_links":{"self":[{"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/product\/222619"}],"collection":[{"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/media\/222620"}],"wp:attachment":[{"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/media?parent=222619"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/product_cat?post=222619"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/product_tag?post=222619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}