{"id":71883,"date":"2020-11-25T16:58:21","date_gmt":"2020-11-25T14:58:21","guid":{"rendered":"https:\/\/odavprint.ee\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/"},"modified":"2020-12-04T12:22:25","modified_gmt":"2020-12-04T10:22:25","slug":"notepad-linen-double-a-a4-70g-50s-mix-intense-pack4","status":"publish","type":"product","link":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/","title":{"rendered":"Notepad linen Double A  A4 70g.50s.Mix Intense (Pack4)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":71884,"template":"","meta":{"inline_featured_image":false},"product_cat":[17184],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.0 (Yoast SEO v23.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Notepad linen Double A A4 70g.50s.Mix Intense (Pack4), hea hinnaga, osta e-pood - Odav Print<\/title>\n<meta name=\"description\" content=\"Osta Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notepad linen Double A A4 70g.50s.Mix Intense (Pack4)\" \/>\n<meta property=\"og:description\" content=\"Osta Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/\" \/>\n<meta property=\"og:site_name\" content=\"Odav Print\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-04T10:22:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/odavprint.ee\/wp-content\/uploads\/2020\/11\/img_20190530_134425.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"330\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;2.10\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/\",\"url\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/\",\"name\":\"Notepad linen Double A A4 70g.50s.Mix Intense (Pack4), hea hinnaga, osta e-pood - Odav Print\",\"isPartOf\":{\"@id\":\"https:\/\/odavprint.ee\/et\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2020\/11\/img_20190530_134425.jpg\",\"datePublished\":\"2020-11-25T14:58:21+00:00\",\"dateModified\":\"2020-12-04T10:22:25+00:00\",\"description\":\"Osta Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud\",\"breadcrumb\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#primaryimage\",\"url\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2020\/11\/img_20190530_134425.jpg\",\"contentUrl\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2020\/11\/img_20190530_134425.jpg\",\"width\":330,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odavprint.ee\/et\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-pood\",\"item\":\"https:\/\/odavprint.ee\/et\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Notepad linen Double A A4 70g.50s.Mix Intense (Pack4)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odavprint.ee\/et\/#website\",\"url\":\"https:\/\/odavprint.ee\/et\/\",\"name\":\"Odav Print\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/odavprint.ee\/et\/#organization\"},\"alternateName\":\"Kassettide, toonerite t\u00e4itmine ja m\u00fc\u00fck.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odavprint.ee\/et\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"et\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/odavprint.ee\/et\/#organization\",\"name\":\"Odav Print O\u00dc\",\"url\":\"https:\/\/odavprint.ee\/et\/\",\"logo\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-organization-logo\"},\"address\":{\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"59.4306504\",\"longitude\":\"24.8095743\"},\"telephone\":[\"53836926\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"info@odavprint.eu\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-place-address\",\"streetAddress\":\"Pae tn 28\",\"addressLocality\":\"Tallinn\",\"postalCode\":\"11415\",\"addressRegion\":\"Harjumaa\",\"addressCountry\":\"EE\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-organization-logo\",\"url\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2018\/10\/odavprint-logo-240.jpg\",\"contentUrl\":\"https:\/\/odavprint.ee\/wp-content\/uploads\/2018\/10\/odavprint-logo-240.jpg\",\"width\":240,\"height\":36,\"caption\":\"Odav Print O\u00dc\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"2.10\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A8858741704730A\/EOL\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Tallinn\" \/>\n<meta name=\"geo.position\" content=\"59.4306504;24.8095743\" \/>\n<meta name=\"geo.region\" content=\"Estonia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Notepad linen Double A A4 70g.50s.Mix Intense (Pack4), hea hinnaga, osta e-pood - Odav Print","description":"Osta Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/","og_locale":"et_EE","og_type":"article","og_title":"Notepad linen Double A A4 70g.50s.Mix Intense (Pack4)","og_description":"Osta Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud","og_url":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/","og_site_name":"Odav Print","article_modified_time":"2020-12-04T10:22:25+00:00","og_image":[{"width":330,"height":500,"url":"https:\/\/odavprint.ee\/wp-content\/uploads\/2020\/11\/img_20190530_134425.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;2.10","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/","url":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/","name":"Notepad linen Double A A4 70g.50s.Mix Intense (Pack4), hea hinnaga, osta e-pood - Odav Print","isPartOf":{"@id":"https:\/\/odavprint.ee\/et\/#website"},"primaryImageOfPage":{"@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#primaryimage"},"image":{"@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#primaryimage"},"thumbnailUrl":"https:\/\/odavprint.ee\/wp-content\/uploads\/2020\/11\/img_20190530_134425.jpg","datePublished":"2020-11-25T14:58:21+00:00","dateModified":"2020-12-04T10:22:25+00:00","description":"Osta Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) Odav Print \u260e +372 5911 9495 \u2714\ufe0f Parim hind Notepad linen Double A A4 70g.50s.Mix Intense (Pack4) jaoks \u26df Kiire kohaletoimetamine Eestis \u2b50 Garanteeritud","breadcrumb":{"@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#primaryimage","url":"https:\/\/odavprint.ee\/wp-content\/uploads\/2020\/11\/img_20190530_134425.jpg","contentUrl":"https:\/\/odavprint.ee\/wp-content\/uploads\/2020\/11\/img_20190530_134425.jpg","width":330,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odavprint.ee\/et\/"},{"@type":"ListItem","position":2,"name":"E-pood","item":"https:\/\/odavprint.ee\/et\/shop\/"},{"@type":"ListItem","position":3,"name":"Notepad linen Double A A4 70g.50s.Mix Intense (Pack4)"}]},{"@type":"WebSite","@id":"https:\/\/odavprint.ee\/et\/#website","url":"https:\/\/odavprint.ee\/et\/","name":"Odav Print","description":"Just another WordPress site","publisher":{"@id":"https:\/\/odavprint.ee\/et\/#organization"},"alternateName":"Kassettide, toonerite t\u00e4itmine ja m\u00fc\u00fck.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odavprint.ee\/et\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"et"},{"@type":["Organization","Place"],"@id":"https:\/\/odavprint.ee\/et\/#organization","name":"Odav Print O\u00dc","url":"https:\/\/odavprint.ee\/et\/","logo":{"@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-organization-logo"},"image":{"@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-organization-logo"},"address":{"@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"59.4306504","longitude":"24.8095743"},"telephone":["53836926"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"info@odavprint.eu"},{"@type":"PostalAddress","@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-place-address","streetAddress":"Pae tn 28","addressLocality":"Tallinn","postalCode":"11415","addressRegion":"Harjumaa","addressCountry":"EE"},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/odavprint.ee\/et\/product\/notepad-linen-double-a-a4-70g-50s-mix-intense-pack4\/#local-main-organization-logo","url":"https:\/\/odavprint.ee\/wp-content\/uploads\/2018\/10\/odavprint-logo-240.jpg","contentUrl":"https:\/\/odavprint.ee\/wp-content\/uploads\/2018\/10\/odavprint-logo-240.jpg","width":240,"height":36,"caption":"Odav Print O\u00dc"}]},"product_price_amount":"2.10","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"A8858741704730A\/EOL","product_condition":"new","geo.placename":"Tallinn","geo.position":{"lat":"59.4306504","long":"24.8095743"},"geo.region":"Estonia"},"_links":{"self":[{"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/product\/71883"}],"collection":[{"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/media\/71884"}],"wp:attachment":[{"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/media?parent=71883"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/product_cat?post=71883"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/odavprint.ee\/et\/wp-json\/wp\/v2\/product_tag?post=71883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}